{"id":1011,"date":"2025-11-19T21:10:04","date_gmt":"2025-11-19T20:10:04","guid":{"rendered":"http:\/\/martaweglinska.pl\/?page_id=1011"},"modified":"2026-02-02T18:48:37","modified_gmt":"2026-02-02T17:48:37","slug":"plynne-rzeczywistosci","status":"publish","type":"page","link":"https:\/\/martaweglinska.pl\/en\/plynne-rzeczywistosci\/","title":{"rendered":"Fluid Realities"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"1011\" class=\"elementor elementor-1011\">\n\t\t\t\t<div class=\"elementor-element elementor-element-12b321f1 e-flex e-con-boxed qodef-elementor-content-no e-con e-parent\" data-id=\"12b321f1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-330dec35 elementor-widget elementor-widget-qi_addons_for_elementor_image_gallery_pinterest\" data-id=\"330dec35\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_image_gallery_pinterest.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-image-gallery-pinterest qodef-qi-fslightbox-popup qodef-popup-gallery qodef-image--hover-zoom qodef-qi-grid qodef-layout--qi-masonry qodef-col-num--3 qodef-responsive--predefined\">\n\t<div class=\"qodef-grid-inner\">\n\t\t\t<div class=\"qodef-qi-grid-masonry-sizer\"><\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-2-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-138\">\n\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1871\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-2-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-2-scaled.jpg 2560w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-2-300x219.jpg 300w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-2-1024x748.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-2-768x561.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-2-1536x1122.jpg 1536w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-2-2048x1496.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-3-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-138\">\n\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1811\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-3-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-3-scaled.jpg 2560w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-3-300x212.jpg 300w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-3-1024x724.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-3-768x543.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-3-1536x1086.jpg 1536w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-3-2048x1448.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-4-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-138\">\n\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1811\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-4-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-4-scaled.jpg 2560w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-4-300x212.jpg 300w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-4-1024x724.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-4-768x543.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-4-1536x1086.jpg 1536w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-4-2048x1448.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-5-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-138\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1803\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-5-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-5-scaled.jpg 2560w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-5-300x211.jpg 300w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-5-1024x721.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-5-768x541.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-5-1536x1082.jpg 1536w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-5-2048x1442.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-6-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-138\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1777\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-6-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-6-scaled.jpg 2560w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-6-300x208.jpg 300w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-6-1024x711.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-6-768x533.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-6-1536x1066.jpg 1536w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-6-2048x1422.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-7-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-138\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1816\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-7-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-7-scaled.jpg 2560w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-7-300x213.jpg 300w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-7-1024x726.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-7-768x545.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-7-1536x1090.jpg 1536w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-7-2048x1453.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-8-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-138\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1816\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-8-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-8-scaled.jpg 2560w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-8-300x213.jpg 300w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-8-1024x726.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-8-768x545.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-8-1536x1090.jpg 1536w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-8-2048x1453.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-9-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-138\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1804\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-9-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-9-scaled.jpg 2560w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-9-300x211.jpg 300w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-9-1024x722.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-9-768x541.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-9-1536x1083.jpg 1536w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-9-2048x1443.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-10-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-138\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1751\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-10-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-10-scaled.jpg 2560w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-10-300x205.jpg 300w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-10-1024x701.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-10-768x525.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-10-1536x1051.jpg 1536w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-10-2048x1401.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-11-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-138\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1814\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-11-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-11-scaled.jpg 2560w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-11-300x213.jpg 300w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-11-1024x726.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-11-768x544.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-11-1536x1088.jpg 1536w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-11-2048x1451.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-12-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-138\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1706\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-12-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-12-scaled.jpg 2560w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-12-300x200.jpg 300w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-12-1024x683.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-12-768x512.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-12-1536x1024.jpg 1536w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-12-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_krajobrazy_relacji2025_GaleriaCentrala_fotAnkaGregorczyk-1-88-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-138\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1706\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_krajobrazy_relacji2025_GaleriaCentrala_fotAnkaGregorczyk-1-88-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_krajobrazy_relacji2025_GaleriaCentrala_fotAnkaGregorczyk-1-88-scaled.jpg 2560w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_krajobrazy_relacji2025_GaleriaCentrala_fotAnkaGregorczyk-1-88-300x200.jpg 300w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_krajobrazy_relacji2025_GaleriaCentrala_fotAnkaGregorczyk-1-88-1024x683.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_krajobrazy_relacji2025_GaleriaCentrala_fotAnkaGregorczyk-1-88-768x512.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_krajobrazy_relacji2025_GaleriaCentrala_fotAnkaGregorczyk-1-88-1536x1024.jpg 1536w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_krajobrazy_relacji2025_GaleriaCentrala_fotAnkaGregorczyk-1-88-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-1-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-138\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1861\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-1-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-1-scaled.jpg 2560w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-1-300x218.jpg 300w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-1-1024x744.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-1-768x558.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-1-1536x1117.jpg 1536w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-1-2048x1489.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-13-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-138\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1706\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-13-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-13-scaled.jpg 2560w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-13-300x200.jpg 300w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-13-1024x683.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-13-768x512.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-13-1536x1024.jpg 1536w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-13-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4502b58 e-flex e-con-boxed qodef-elementor-content-no e-con e-parent\" data-id=\"4502b58\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0d3dd57 e-con-full e-flex qodef-elementor-content-no e-con e-child\" data-id=\"0d3dd57\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7966b4f6 elementor-widget elementor-widget-qi_addons_for_elementor_section_title\" data-id=\"7966b4f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-section-title qodef-decoration--italic qodef-link--underline-draw qodef-subtitle-icon--left\">\n\t\t\t\t\t\t<h2 class=\"qodef-m-title\">\n\t\tFluid Realities\t<\/h2>\n\t\t\t<div class=\"qodef-m-text\"><p><i><span style=\"font-weight: 400\">inkjet\/digital print and drawing with art crayons on paper, 29.7x21 cm and 32.5x45 cm, 2024-2025<\/span><\/i><\/p><p>\u00a0<\/p><p><span style=\"font-weight: 400\">The works combine photographs taken during field research (in areas of natural value) with complementary abstract drawings. The collages refer to the mechanisms occurring in the environment - the constant dynamics of change: the transformation and interpenetration of the elements, the mixing of water, vegetation, earth, and rocks.<\/span><\/p><p>\u00a0<\/p><p><span style=\"font-weight: 400\">The drawing is a hyperrealistic continuation of the photograph, developing its abstract potential.<\/span><\/p><p>\u00a0<\/p><p><span style=\"font-weight: 400\">The photographs come from protected areas: the \u015arubita Reserve, the Prof. Zenon Klemensiewicz Reserve on Policy, the Drawski Landscape Park, and the Babia G\u00f3ra National Park. <\/span><\/p><\/div>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e2c4f78 e-con-full e-flex qodef-elementor-content-no e-con e-child\" data-id=\"e2c4f78\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-efbfe9b e-flex e-con-boxed qodef-elementor-content-no e-con e-parent\" data-id=\"efbfe9b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b71d04c elementor-widget elementor-widget-qi_addons_for_elementor_info_button\" data-id=\"b71d04c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_info_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a class=\"qodef-shortcode qodef-m qodef-qi-info-button qodef-html--link qodef-layout--outlined qodef-type--standard qodef-icon--left qodef-hover--icon-move-horizontal-short\" href=\"https:\/\/martaweglinska.pl\/en\/portfolio\/\" target=\"_self\">\n\t<div class=\"qodef-m-text-holder\">\n\t<span class=\"qodef-m-text\">Back to Works <\/span>\n\t\t\t<span class=\"qodef-m-icon\">\n\t\t<span class=\"qodef-m-icon-inner\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-left\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.7 239l136-136c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9L127.9 256l96.4 96.4c9.4 9.4 9.4 24.6 0 33.9L201.7 409c-9.4 9.4-24.6 9.4-33.9 0l-136-136c-9.5-9.4-9.5-24.6-.1-34z\"><\/path><\/svg>\t\t\t\t\t<\/span>\n\t<\/span>\n\t<\/div>\n\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>P\u0142ynne Rzeczywisto\u015bci druk atramentowy\/cyfrowy i rysunek kredkami artystycznymi na papierze, 29,7&#215;21 cm oraz 32,5&#215;45 cm, 2024-2025 \u00a0 Prace \u0142\u0105cz\u0105 fotografie wykonane podczas bada\u0144 terenowych (na obszarach cennych przyrodniczo) z dope\u0142niaj\u0105cymi je abstrakcyjnymi rysunkami. Kola\u017ce odnosz\u0105 si\u0119 do mechanizm\u00f3w zachodz\u0105cych w \u015brodowisku &#8211; nieustannej dynamice zmian: transformacji i przenikaniu \u017cywio\u0142\u00f3w, przemieszaniu si\u0119 wody, ro\u015blinno\u015bci, ziemi i [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1013,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"qi-full-width.php","meta":{"footnotes":""},"class_list":["post-1011","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Liquid Realities - Marta W\u0119gli\u0144ska - Environmental Research Collages<\/title>\n<meta name=\"description\" content=\"Collages blending field photographs from protected areas with abstract drawing, exploring environmental dynamics, transformations, and interconnections of natural elements.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/martaweglinska.pl\/en\/plynne-rzeczywistosci\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Liquid Realities - Marta W\u0119gli\u0144ska - Environmental Research Collages\" \/>\n<meta property=\"og:description\" content=\"Collages blending field photographs from protected areas with abstract drawing, exploring environmental dynamics, transformations, and interconnections of natural elements.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/martaweglinska.pl\/en\/plynne-rzeczywistosci\/\" \/>\n<meta property=\"og:site_name\" content=\"Marta W\u0119gli\u0144ska\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kobalt.migrating.platform\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-02T17:48:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-13-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1706\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/martaweglinska.pl\\\/plynne-rzeczywistosci\\\/\",\"url\":\"https:\\\/\\\/martaweglinska.pl\\\/plynne-rzeczywistosci\\\/\",\"name\":\"Liquid Realities - Marta W\u0119gli\u0144ska - Environmental Research Collages\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/martaweglinska.pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/martaweglinska.pl\\\/plynne-rzeczywistosci\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/martaweglinska.pl\\\/plynne-rzeczywistosci\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/martaweglinska.pl\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-13-scaled.jpg\",\"datePublished\":\"2025-11-19T20:10:04+00:00\",\"dateModified\":\"2026-02-02T17:48:37+00:00\",\"description\":\"Collages blending field photographs from protected areas with abstract drawing, exploring environmental dynamics, transformations, and interconnections of natural elements.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/martaweglinska.pl\\\/plynne-rzeczywistosci\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/martaweglinska.pl\\\/plynne-rzeczywistosci\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/martaweglinska.pl\\\/plynne-rzeczywistosci\\\/#primaryimage\",\"url\":\"https:\\\/\\\/martaweglinska.pl\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-13-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/martaweglinska.pl\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-13-scaled.jpg\",\"width\":2560,\"height\":1706},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/martaweglinska.pl\\\/plynne-rzeczywistosci\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\\\/\\\/martaweglinska.pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"P\u0142ynne rzeczywisto\u015bci\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/martaweglinska.pl\\\/#website\",\"url\":\"https:\\\/\\\/martaweglinska.pl\\\/\",\"name\":\"Marta W\u0119gli\u0144ska\",\"description\":\"Portfolio\",\"publisher\":{\"@id\":\"https:\\\/\\\/martaweglinska.pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/martaweglinska.pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/martaweglinska.pl\\\/#organization\",\"name\":\"Marta W\u0119gli\u0144ska\",\"url\":\"https:\\\/\\\/martaweglinska.pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/martaweglinska.pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/martaweglinska.pl\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Marta-Weglinska-e1763409767210.png\",\"contentUrl\":\"https:\\\/\\\/martaweglinska.pl\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Marta-Weglinska-e1763409767210.png\",\"width\":1170,\"height\":640,\"caption\":\"Marta W\u0119gli\u0144ska\"},\"image\":{\"@id\":\"https:\\\/\\\/martaweglinska.pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kobalt.migrating.platform\",\"https:\\\/\\\/www.instagram.com\\\/marta.weglinska\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Liquid Realities - Marta W\u0119gli\u0144ska - Environmental Research Collages","description":"Collages blending field photographs from protected areas with abstract drawing, exploring environmental dynamics, transformations, and interconnections of natural elements.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/martaweglinska.pl\/en\/plynne-rzeczywistosci\/","og_locale":"en_GB","og_type":"article","og_title":"Liquid Realities - Marta W\u0119gli\u0144ska - Environmental Research Collages","og_description":"Collages blending field photographs from protected areas with abstract drawing, exploring environmental dynamics, transformations, and interconnections of natural elements.","og_url":"https:\/\/martaweglinska.pl\/en\/plynne-rzeczywistosci\/","og_site_name":"Marta W\u0119gli\u0144ska","article_publisher":"https:\/\/www.facebook.com\/kobalt.migrating.platform","article_modified_time":"2026-02-02T17:48:37+00:00","og_image":[{"width":2560,"height":1706,"url":"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-13-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/martaweglinska.pl\/plynne-rzeczywistosci\/","url":"https:\/\/martaweglinska.pl\/plynne-rzeczywistosci\/","name":"Liquid Realities - Marta W\u0119gli\u0144ska - Environmental Research Collages","isPartOf":{"@id":"https:\/\/martaweglinska.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/martaweglinska.pl\/plynne-rzeczywistosci\/#primaryimage"},"image":{"@id":"https:\/\/martaweglinska.pl\/plynne-rzeczywistosci\/#primaryimage"},"thumbnailUrl":"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-13-scaled.jpg","datePublished":"2025-11-19T20:10:04+00:00","dateModified":"2026-02-02T17:48:37+00:00","description":"Collages blending field photographs from protected areas with abstract drawing, exploring environmental dynamics, transformations, and interconnections of natural elements.","breadcrumb":{"@id":"https:\/\/martaweglinska.pl\/plynne-rzeczywistosci\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/martaweglinska.pl\/plynne-rzeczywistosci\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/martaweglinska.pl\/plynne-rzeczywistosci\/#primaryimage","url":"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-13-scaled.jpg","contentUrl":"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Plynne_rzeczywistosci_LiquidReality2025-13-scaled.jpg","width":2560,"height":1706},{"@type":"BreadcrumbList","@id":"https:\/\/martaweglinska.pl\/plynne-rzeczywistosci\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/martaweglinska.pl\/"},{"@type":"ListItem","position":2,"name":"P\u0142ynne rzeczywisto\u015bci"}]},{"@type":"WebSite","@id":"https:\/\/martaweglinska.pl\/#website","url":"https:\/\/martaweglinska.pl\/","name":"Marta W\u0119gli\u0144ska","description":"Portfolio","publisher":{"@id":"https:\/\/martaweglinska.pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/martaweglinska.pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/martaweglinska.pl\/#organization","name":"Marta W\u0119gli\u0144ska","url":"https:\/\/martaweglinska.pl\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/martaweglinska.pl\/#\/schema\/logo\/image\/","url":"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/Marta-Weglinska-e1763409767210.png","contentUrl":"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/Marta-Weglinska-e1763409767210.png","width":1170,"height":640,"caption":"Marta W\u0119gli\u0144ska"},"image":{"@id":"https:\/\/martaweglinska.pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kobalt.migrating.platform","https:\/\/www.instagram.com\/marta.weglinska"]}]}},"_links":{"self":[{"href":"https:\/\/martaweglinska.pl\/en\/wp-json\/wp\/v2\/pages\/1011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/martaweglinska.pl\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/martaweglinska.pl\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/martaweglinska.pl\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/martaweglinska.pl\/en\/wp-json\/wp\/v2\/comments?post=1011"}],"version-history":[{"count":25,"href":"https:\/\/martaweglinska.pl\/en\/wp-json\/wp\/v2\/pages\/1011\/revisions"}],"predecessor-version":[{"id":2065,"href":"https:\/\/martaweglinska.pl\/en\/wp-json\/wp\/v2\/pages\/1011\/revisions\/2065"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/martaweglinska.pl\/en\/wp-json\/wp\/v2\/media\/1013"}],"wp:attachment":[{"href":"https:\/\/martaweglinska.pl\/en\/wp-json\/wp\/v2\/media?parent=1011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}