{"id":989,"date":"2025-11-19T21:02:40","date_gmt":"2025-11-19T20:02:40","guid":{"rendered":"http:\/\/martaweglinska.pl\/?page_id=989"},"modified":"2026-02-02T19:17:31","modified_gmt":"2026-02-02T18:17:31","slug":"duch-wody","status":"publish","type":"page","link":"https:\/\/martaweglinska.pl\/en\/duch-wody\/","title":{"rendered":"Duch wody"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"989\" class=\"elementor elementor-989\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7f183070 e-flex e-con-boxed qodef-elementor-content-no e-con e-parent\" data-id=\"7f183070\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-446b343f elementor-widget elementor-widget-qi_addons_for_elementor_image_gallery_pinterest\" data-id=\"446b343f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_image_gallery_pinterest.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-image-gallery-pinterest qodef-qi-fslightbox-popup qodef-popup-gallery qodef-image--hover-zoom qodef-qi-grid qodef-layout--qi-masonry qodef-col-num--2 qodef-responsive--predefined\">\n\t<div class=\"qodef-grid-inner\">\n\t\t\t<div class=\"qodef-qi-grid-masonry-sizer\"><\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_krajobrazy_relacji2025_GaleriaCentrala_fotMarekZakrzewski-85-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-95\">\n\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1706\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_krajobrazy_relacji2025_GaleriaCentrala_fotMarekZakrzewski-85-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_krajobrazy_relacji2025_GaleriaCentrala_fotMarekZakrzewski-85-scaled.jpg 2560w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_krajobrazy_relacji2025_GaleriaCentrala_fotMarekZakrzewski-85-300x200.jpg 300w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_krajobrazy_relacji2025_GaleriaCentrala_fotMarekZakrzewski-85-1024x683.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_krajobrazy_relacji2025_GaleriaCentrala_fotMarekZakrzewski-85-768x512.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_krajobrazy_relacji2025_GaleriaCentrala_fotMarekZakrzewski-85-1536x1024.jpg 1536w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_krajobrazy_relacji2025_GaleriaCentrala_fotMarekZakrzewski-85-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_krajobrazy_relacji2025_GaleriaCentrala_fotAnkaGregorczyk-2-87-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-95\">\n\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1706\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_krajobrazy_relacji2025_GaleriaCentrala_fotAnkaGregorczyk-2-87-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_krajobrazy_relacji2025_GaleriaCentrala_fotAnkaGregorczyk-2-87-scaled.jpg 2560w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_krajobrazy_relacji2025_GaleriaCentrala_fotAnkaGregorczyk-2-87-300x200.jpg 300w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_krajobrazy_relacji2025_GaleriaCentrala_fotAnkaGregorczyk-2-87-1024x683.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_krajobrazy_relacji2025_GaleriaCentrala_fotAnkaGregorczyk-2-87-768x512.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_krajobrazy_relacji2025_GaleriaCentrala_fotAnkaGregorczyk-2-87-1536x1024.jpg 1536w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_krajobrazy_relacji2025_GaleriaCentrala_fotAnkaGregorczyk-2-87-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_krajobrazy_relacji2025_GaleriaCentrala_fotAnkaGregorczyk-1-89-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-95\">\n\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1706\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_krajobrazy_relacji2025_GaleriaCentrala_fotAnkaGregorczyk-1-89-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_krajobrazy_relacji2025_GaleriaCentrala_fotAnkaGregorczyk-1-89-scaled.jpg 2560w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_krajobrazy_relacji2025_GaleriaCentrala_fotAnkaGregorczyk-1-89-300x200.jpg 300w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_krajobrazy_relacji2025_GaleriaCentrala_fotAnkaGregorczyk-1-89-1024x683.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_krajobrazy_relacji2025_GaleriaCentrala_fotAnkaGregorczyk-1-89-768x512.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_krajobrazy_relacji2025_GaleriaCentrala_fotAnkaGregorczyk-1-89-1536x1024.jpg 1536w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_krajobrazy_relacji2025_GaleriaCentrala_fotAnkaGregorczyk-1-89-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_Chociaz_twarde_skaly_2025_MuzeumDabrowskiego-2-69-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-95\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2391\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_Chociaz_twarde_skaly_2025_MuzeumDabrowskiego-2-69-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_Chociaz_twarde_skaly_2025_MuzeumDabrowskiego-2-69-scaled.jpg 2560w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_Chociaz_twarde_skaly_2025_MuzeumDabrowskiego-2-69-300x280.jpg 300w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_Chociaz_twarde_skaly_2025_MuzeumDabrowskiego-2-69-1024x956.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_Chociaz_twarde_skaly_2025_MuzeumDabrowskiego-2-69-768x717.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_Chociaz_twarde_skaly_2025_MuzeumDabrowskiego-2-69-1536x1434.jpg 1536w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_Chociaz_twarde_skaly_2025_MuzeumDabrowskiego-2-69-2048x1912.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_Chociaz_twarde_skaly_2025_MuzeumDabrowskiego-1-70-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-95\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2467\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_Chociaz_twarde_skaly_2025_MuzeumDabrowskiego-1-70-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_Chociaz_twarde_skaly_2025_MuzeumDabrowskiego-1-70-scaled.jpg 2560w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_Chociaz_twarde_skaly_2025_MuzeumDabrowskiego-1-70-300x289.jpg 300w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_Chociaz_twarde_skaly_2025_MuzeumDabrowskiego-1-70-1024x987.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_Chociaz_twarde_skaly_2025_MuzeumDabrowskiego-1-70-768x740.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_Chociaz_twarde_skaly_2025_MuzeumDabrowskiego-1-70-1536x1480.jpg 1536w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/XMartaWeglinska_Chociaz_twarde_skaly_2025_MuzeumDabrowskiego-1-70-2048x1974.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2bdf3ac e-flex e-con-boxed qodef-elementor-content-no e-con e-parent\" data-id=\"2bdf3ac\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4739a86 e-con-full e-flex qodef-elementor-content-no e-con e-child\" data-id=\"4739a86\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-305b05da elementor-widget elementor-widget-qi_addons_for_elementor_section_title\" data-id=\"305b05da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-section-title qodef-decoration--italic qodef-link--underline-draw qodef-subtitle-icon--left\">\n\t\t\t\t\t\t<h2 class=\"qodef-m-title\">\n\t\tSpirit of Water\t<\/h2>\n\t\t\t<div class=\"qodef-m-text\"><p><i><span style=\"font-weight: 400\">Flag, mask, glove, pillow of the Spirit of Water - cyanotypes on cotton (various formats), pattern and sewing: Berenika Pyza; series of digital photographs; large-format scrolls - photographs and scans of graphics; cyanotypes on paper, A4, 2024-2025<\/span><\/i><\/p><p>\u00a0<\/p><p><span style=\"font-weight: 400\">The figure of the Spirit of Water is inspired by Slavic beliefs related to the cult of water and creatures inhabiting aquatic ecosystems (Water Maiden, Rusalka, Boginka, Dziwo\u017cona, Wi\u0142a, Brzegina, Brzeginka). The objects are covered with water motifs, including photographs of aquatic ecosystems where I conducted field research in 2022\u20132024 (e.g., Rogali\u0144ski Landscape Park, Puszcza Zielonki Landscape Park, Krajkowo Reserve).\u00a0<\/span><\/p><p>\u00a0<\/p><p><span style=\"font-weight: 400\">The project was initially created with direct reference to the natural environment of Poland, but in the course of further work it became a more universal concept.<\/span><\/p><\/div>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c683b0c e-con-full e-flex qodef-elementor-content-no e-con e-child\" data-id=\"c683b0c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-df1aa8c e-flex e-con-boxed qodef-elementor-content-no e-con e-parent\" data-id=\"df1aa8c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dd8ee9f elementor-widget elementor-widget-qi_addons_for_elementor_image_gallery_pinterest\" data-id=\"dd8ee9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_image_gallery_pinterest.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-image-gallery-pinterest qodef-qi-fslightbox-popup qodef-popup-gallery qodef-image--hover-zoom qodef-qi-grid qodef-layout--qi-masonry qodef-col-num--2 qodef-responsive--predefined\">\n\t<div class=\"qodef-grid-inner\">\n\t\t\t<div class=\"qodef-qi-grid-masonry-sizer\"><\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-20246-32-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-315\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1706\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-20246-32-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-20246-32-scaled.jpg 2560w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-20246-32-300x200.jpg 300w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-20246-32-1024x683.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-20246-32-768x512.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-20246-32-1536x1024.jpg 1536w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-20246-32-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2020\/10\/MartaWeglinska_krajobrazyRelacji_GaleriaCentrala2025_fotMarekZakrzewski-1-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-315\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1706\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2020\/10\/MartaWeglinska_krajobrazyRelacji_GaleriaCentrala2025_fotMarekZakrzewski-1-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2020\/10\/MartaWeglinska_krajobrazyRelacji_GaleriaCentrala2025_fotMarekZakrzewski-1-scaled.jpg 2560w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2020\/10\/MartaWeglinska_krajobrazyRelacji_GaleriaCentrala2025_fotMarekZakrzewski-1-300x200.jpg 300w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2020\/10\/MartaWeglinska_krajobrazyRelacji_GaleriaCentrala2025_fotMarekZakrzewski-1-1024x683.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2020\/10\/MartaWeglinska_krajobrazyRelacji_GaleriaCentrala2025_fotMarekZakrzewski-1-768x512.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2020\/10\/MartaWeglinska_krajobrazyRelacji_GaleriaCentrala2025_fotMarekZakrzewski-1-1536x1024.jpg 1536w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2020\/10\/MartaWeglinska_krajobrazyRelacji_GaleriaCentrala2025_fotMarekZakrzewski-1-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-92e479c e-flex e-con-boxed qodef-elementor-content-no e-con e-parent\" data-id=\"92e479c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-612b469 e-con-full e-flex qodef-elementor-content-no e-con e-child\" data-id=\"612b469\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9e5308f elementor-widget elementor-widget-qi_addons_for_elementor_section_title\" data-id=\"9e5308f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-section-title qodef-decoration--italic qodef-link--underline-draw qodef-subtitle-icon--left\">\n\t\t\t\t\t\t\t\t<div class=\"qodef-m-text\"><p><b>The Flag of Water<\/b><\/p><p><span style=\"font-weight: 400\">The flag with the slogan \u201cWater is the beginning of all things\u201d is the flag of all waters - the flag of the entire Earth, waters undivided by human borders. The quote on the fabric is taken from the ancient Greek philosopher Thales of Miletus.<\/span><\/p><\/div>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7215c70 e-con-full e-flex qodef-elementor-content-no e-con e-child\" data-id=\"7215c70\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4555ddf e-flex e-con-boxed qodef-elementor-content-no e-con e-parent\" data-id=\"4555ddf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0f871f6 elementor-widget elementor-widget-qi_addons_for_elementor_image_gallery_pinterest\" data-id=\"0f871f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_image_gallery_pinterest.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-image-gallery-pinterest qodef-qi-fslightbox-popup qodef-popup-gallery qodef-image--hover-zoom qodef-qi-grid qodef-layout--qi-masonry qodef-col-num--2 qodef-responsive--predefined\">\n\t<div class=\"qodef-grid-inner\">\n\t\t\t<div class=\"qodef-qi-grid-masonry-sizer\"><\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-20248-34-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-682\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1706\" height=\"2560\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-20248-34-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-20248-34-scaled.jpg 1706w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-20248-34-200x300.jpg 200w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-20248-34-683x1024.jpg 683w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-20248-34-768x1152.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-20248-34-1024x1536.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-20248-34-1365x2048.jpg 1365w\" sizes=\"(max-width: 1706px) 100vw, 1706px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-20247-33-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-682\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1706\" height=\"2560\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-20247-33-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-20247-33-scaled.jpg 1706w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-20247-33-200x300.jpg 200w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-20247-33-683x1024.jpg 683w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-20247-33-768x1152.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-20247-33-1024x1536.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-20247-33-1365x2048.jpg 1365w\" sizes=\"(max-width: 1706px) 100vw, 1706px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-202410-36-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-682\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1706\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-202410-36-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-202410-36-scaled.jpg 2560w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-202410-36-300x200.jpg 300w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-202410-36-1024x683.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-202410-36-768x512.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-202410-36-1536x1024.jpg 1536w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-202410-36-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-20249-35-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-682\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1706\" height=\"2560\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-20249-35-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-20249-35-scaled.jpg 1706w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-20249-35-200x300.jpg 200w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-20249-35-683x1024.jpg 683w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-20249-35-768x1152.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-20249-35-1024x1536.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Water_spirit_Rogalinski_Landscape_Park-20249-35-1365x2048.jpg 1365w\" sizes=\"(max-width: 1706px) 100vw, 1706px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-8-42-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-682\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1706\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-8-42-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-8-42-scaled.jpg 2560w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-8-42-300x200.jpg 300w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-8-42-1024x683.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-8-42-768x512.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-8-42-1536x1024.jpg 1536w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-8-42-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-5-39-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-682\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1706\" height=\"2560\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-5-39-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-5-39-scaled.jpg 1706w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-5-39-200x300.jpg 200w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-5-39-683x1024.jpg 683w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-5-39-768x1152.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-5-39-1024x1536.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-5-39-1365x2048.jpg 1365w\" sizes=\"(max-width: 1706px) 100vw, 1706px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5f9c9b4 e-flex e-con-boxed qodef-elementor-content-no e-con e-parent\" data-id=\"5f9c9b4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2f7b56d e-con-full e-flex qodef-elementor-content-no e-con e-child\" data-id=\"2f7b56d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6b79b68 elementor-widget elementor-widget-qi_addons_for_elementor_section_title\" data-id=\"6b79b68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-section-title qodef-decoration--italic qodef-link--underline-draw qodef-subtitle-icon--left\">\n\t\t\t\t\t\t\t\t<div class=\"qodef-m-text\"><p><b>The Water Spirit glove, mask and pillow<\/b><\/p><p><span style=\"font-weight: 400\">The Water Spirit glove and mask were created to hide the human body and blend into the landscape. You can lay your head on the water pillow, fall asleep, and dream of wild rivers, lakes, wetlands, and floodplains. The pillow can also be a soft shield\u2014providing protection, allowing you to disappear for a moment, to merge with the natural environment.<\/span><\/p><\/div>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aa1f5b4 e-con-full e-flex qodef-elementor-content-no e-con e-child\" data-id=\"aa1f5b4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c43c2b2 e-flex e-con-boxed qodef-elementor-content-no e-con e-parent\" data-id=\"c43c2b2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6bbf7cc e-con-full e-flex qodef-elementor-content-no e-con e-child\" data-id=\"6bbf7cc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5b47fe0 elementor-widget elementor-widget-qi_addons_for_elementor_section_title\" data-id=\"5b47fe0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-section-title qodef-decoration--italic qodef-link--underline-draw qodef-subtitle-icon--left\">\n\t\t\t\t\t\t\t\t<div class=\"qodef-m-text\"><p><b>Site-specific artwork\/performance for nature<\/b><\/p><p><span style=\"font-weight: 400\">The Spirit of Water is a performative concept \u2013 the final character was photographed in various landscapes and locations of natural value in Poland and Indonesia. The activities carried out in Indonesia were part of an artist residency at the Jatiwangi Art Factory. The photographs were taken in collaboration with photographers Adhiwinanto Semali and Nur Khamdan.<\/span><\/p><\/div>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-997ddc0 e-con-full e-flex qodef-elementor-content-no e-con e-child\" data-id=\"997ddc0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-be913be e-flex e-con-boxed qodef-elementor-content-no e-con e-parent\" data-id=\"be913be\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c1886a7 elementor-widget elementor-widget-qi_addons_for_elementor_image_gallery_pinterest\" data-id=\"c1886a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_image_gallery_pinterest.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-image-gallery-pinterest qodef-qi-fslightbox-popup qodef-popup-gallery qodef-image--hover-zoom qodef-qi-grid qodef-layout--qi-masonry qodef-col-num--2 qodef-responsive--predefined\">\n\t<div class=\"qodef-grid-inner\">\n\t\t\t<div class=\"qodef-qi-grid-masonry-sizer\"><\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-13-49-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-651\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1706\" height=\"2560\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-13-49-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-13-49-scaled.jpg 1706w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-13-49-200x300.jpg 200w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-13-49-683x1024.jpg 683w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-13-49-768x1152.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-13-49-1024x1536.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-13-49-1365x2048.jpg 1365w\" sizes=\"(max-width: 1706px) 100vw, 1706px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-12-48-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-651\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"739\" height=\"2560\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-12-48-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-12-48-scaled.jpg 739w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-12-48-87x300.jpg 87w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-12-48-296x1024.jpg 296w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-12-48-768x2661.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-12-48-443x1536.jpg 443w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-12-48-591x2048.jpg 591w\" sizes=\"(max-width: 739px) 100vw, 739px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-11-47-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-651\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1750\" height=\"2560\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-11-47-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-11-47-scaled.jpg 1750w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-11-47-205x300.jpg 205w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-11-47-700x1024.jpg 700w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-11-47-768x1124.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-11-47-1050x1536.jpg 1050w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-11-47-1400x2048.jpg 1400w\" sizes=\"(max-width: 1750px) 100vw, 1750px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-9-44-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-651\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1525\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-9-44-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-9-44-scaled.jpg 2560w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-9-44-300x179.jpg 300w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-9-44-1024x610.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-9-44-768x458.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-9-44-1536x915.jpg 1536w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-9-44-2048x1220.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-4-38-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-651\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2487\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-4-38-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-4-38-scaled.jpg 2560w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-4-38-300x291.jpg 300w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-4-38-1024x995.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-4-38-768x746.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-4-38-1536x1492.jpg 1536w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-4-38-2048x1989.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-1-45-1-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-651\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1032\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-1-45-1-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-1-45-1-scaled.jpg 2560w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-1-45-1-300x121.jpg 300w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-1-45-1-1024x413.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-1-45-1-768x310.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-1-45-1-1536x619.jpg 1536w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-1-45-1-2048x826.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-10-46-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-651\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1706\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-10-46-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-10-46-scaled.jpg 2560w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-10-46-300x200.jpg 300w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-10-46-1024x683.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-10-46-768x512.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-10-46-1536x1024.jpg 1536w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-10-46-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-3-43-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-651\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1911\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-3-43-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-3-43-scaled.jpg 2560w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-3-43-300x224.jpg 300w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-3-43-1024x764.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-3-43-768x573.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-3-43-1536x1147.jpg 1536w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-3-43-2048x1529.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-2-37-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-651\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2160\" height=\"2560\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-2-37-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-2-37-scaled.jpg 2160w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-2-37-253x300.jpg 253w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-2-37-864x1024.jpg 864w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-2-37-768x910.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-2-37-1296x1536.jpg 1296w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-2-37-1728x2048.jpg 1728w\" sizes=\"(max-width: 2160px) 100vw, 2160px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-81b88c3 e-flex e-con-boxed qodef-elementor-content-no e-con e-parent\" data-id=\"81b88c3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0a85ae1 elementor-widget elementor-widget-qi_addons_for_elementor_image_gallery_pinterest\" data-id=\"0a85ae1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_image_gallery_pinterest.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-image-gallery-pinterest qodef-qi-fslightbox-popup qodef-popup-gallery qodef-image--hover-zoom qodef-qi-grid qodef-layout--qi-masonry qodef-col-num--2 qodef-responsive--predefined\">\n\t<div class=\"qodef-grid-inner\">\n\t\t\t<div class=\"qodef-qi-grid-masonry-sizer\"><\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-7-31-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-984\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1706\" height=\"2560\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-7-31-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-7-31-scaled.jpg 1706w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-7-31-200x300.jpg 200w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-7-31-683x1024.jpg 683w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-7-31-768x1152.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-7-31-1024x1536.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-7-31-1365x2048.jpg 1365w\" sizes=\"(max-width: 1706px) 100vw, 1706px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-6-30-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-984\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1706\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-6-30-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-6-30-scaled.jpg 2560w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-6-30-300x200.jpg 300w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-6-30-1024x683.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-6-30-768x512.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-6-30-1536x1024.jpg 1536w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-6-30-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-5-29-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-984\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1706\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-5-29-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-5-29-scaled.jpg 2560w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-5-29-300x200.jpg 300w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-5-29-1024x683.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-5-29-768x512.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-5-29-1536x1024.jpg 1536w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-5-29-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-4-28-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-984\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1706\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-4-28-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-4-28-scaled.jpg 2560w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-4-28-300x200.jpg 300w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-4-28-1024x683.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-4-28-768x512.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-4-28-1536x1024.jpg 1536w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-4-28-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-3-27-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-984\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1706\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-3-27-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-3-27-scaled.jpg 2560w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-3-27-300x200.jpg 300w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-3-27-1024x683.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-3-27-768x512.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-3-27-1536x1024.jpg 1536w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-3-27-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-2-26-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-984\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1706\" height=\"2560\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-2-26-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-2-26-scaled.jpg 1706w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-2-26-200x300.jpg 200w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-2-26-683x1024.jpg 683w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-2-26-768x1152.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-2-26-1024x1536.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-2-26-1365x2048.jpg 1365w\" sizes=\"(max-width: 1706px) 100vw, 1706px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-1-25-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-984\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1706\" height=\"2560\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-1-25-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-1-25-scaled.jpg 1706w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-1-25-200x300.jpg 200w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-1-25-683x1024.jpg 683w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-1-25-768x1152.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-1-25-1024x1536.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_flag_of_the_water__flaga_wody_2024-1-25-1365x2048.jpg 1365w\" sizes=\"(max-width: 1706px) 100vw, 1706px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e5f8e45 e-flex e-con-boxed qodef-elementor-content-no e-con e-parent\" data-id=\"e5f8e45\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9fa7463 e-con-full e-flex qodef-elementor-content-no e-con e-child\" data-id=\"9fa7463\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-86f51e6 elementor-widget elementor-widget-qi_addons_for_elementor_section_title\" data-id=\"86f51e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-section-title qodef-decoration--italic qodef-link--underline-draw qodef-subtitle-icon--left\">\n\t\t\t\t\t\t\t\t<div class=\"qodef-m-text\"><p class=\"translation-block\"><b>Spirit of Water (Body of Water)<\/b><span style=\"font-weight: 400\"> \u2013 cyanotypes on A4 paper \u2013 is a series of works showing maps of the diverse terrain of selected water reservoirs in Greater Poland (based on data from geoportal.gov.pl). The works draw attention to the sculptural potential of water. The cyanotype \u201cWater\u201d is a list of nouns, verbs, and adjectives illustrating the omnipresence of water in human life and the environment. The work is based on information from the Dictionary of Stereotypes and Folk Symbols (J. Bartmi\u0144ski).<\/p><\/div>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b9d1d07 e-con-full e-flex qodef-elementor-content-no e-con e-child\" data-id=\"b9d1d07\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4b3f1f2 e-flex e-con-boxed qodef-elementor-content-no e-con e-parent\" data-id=\"4b3f1f2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a9e8a65 elementor-widget elementor-widget-qi_addons_for_elementor_image_gallery_pinterest\" data-id=\"a9e8a65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_image_gallery_pinterest.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-image-gallery-pinterest qodef-qi-fslightbox-popup qodef-popup-gallery qodef-image--hover-zoom qodef-qi-grid qodef-layout--qi-masonry qodef-col-num--3 qodef-responsive--predefined\">\n\t<div class=\"qodef-grid-inner\">\n\t\t\t<div class=\"qodef-qi-grid-masonry-sizer\"><\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-1.jpg\" data-type=\"image\" data-fslightbox=\"gallery-332\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1414\" height=\"2048\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-1.jpg 1414w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-1-207x300.jpg 207w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-1-707x1024.jpg 707w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-1-768x1112.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-1-1061x1536.jpg 1061w\" sizes=\"(max-width: 1414px) 100vw, 1414px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-7.jpg\" data-type=\"image\" data-fslightbox=\"gallery-332\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1391\" height=\"2048\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-7.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-7.jpg 1391w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-7-204x300.jpg 204w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-7-696x1024.jpg 696w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-7-768x1131.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-7-1043x1536.jpg 1043w\" sizes=\"(max-width: 1391px) 100vw, 1391px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-6.jpg\" data-type=\"image\" data-fslightbox=\"gallery-332\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1425\" height=\"2048\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-6.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-6.jpg 1425w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-6-209x300.jpg 209w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-6-713x1024.jpg 713w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-6-768x1104.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-6-1069x1536.jpg 1069w\" sizes=\"(max-width: 1425px) 100vw, 1425px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-4.jpg\" data-type=\"image\" data-fslightbox=\"gallery-332\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1470\" height=\"2048\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-4.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-4.jpg 1470w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-4-215x300.jpg 215w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-4-735x1024.jpg 735w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-4-768x1070.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-4-1103x1536.jpg 1103w\" sizes=\"(max-width: 1470px) 100vw, 1470px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-2.jpg\" data-type=\"image\" data-fslightbox=\"gallery-332\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1428\" height=\"2048\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-2.jpg 1428w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-2-209x300.jpg 209w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-2-714x1024.jpg 714w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-2-768x1101.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-2-1071x1536.jpg 1071w\" sizes=\"(max-width: 1428px) 100vw, 1428px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-3.jpg\" data-type=\"image\" data-fslightbox=\"gallery-332\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1425\" height=\"2048\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-3.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-3.jpg 1425w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-3-209x300.jpg 209w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-3-713x1024.jpg 713w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-3-768x1104.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-3-1069x1536.jpg 1069w\" sizes=\"(max-width: 1425px) 100vw, 1425px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-5.jpg\" data-type=\"image\" data-fslightbox=\"gallery-332\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1430\" src=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-5.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-5.jpg 2048w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-5-300x209.jpg 300w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-5-1024x715.jpg 1024w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-5-768x536.jpg 768w, https:\/\/martaweglinska.pl\/wp-content\/uploads\/2026\/01\/MartaWeglinska_Duch_Wody_Spirit_of_water_cyjanotypia_2024-5-1536x1073.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2c13e94 e-flex e-con-boxed qodef-elementor-content-no e-con e-parent\" data-id=\"2c13e94\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eef1dbd elementor-widget elementor-widget-qi_addons_for_elementor_info_button\" data-id=\"eef1dbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_info_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a class=\"qodef-shortcode qodef-m qodef-qi-info-button qodef-html--link qodef-layout--outlined qodef-type--standard qodef-icon--left qodef-hover--icon-move-horizontal-short\" href=\"https:\/\/martaweglinska.pl\/en\/portfolio\/\" target=\"_self\">\n\t<div class=\"qodef-m-text-holder\">\n\t<span class=\"qodef-m-text\">Back to Works <\/span>\n\t\t\t<span class=\"qodef-m-icon\">\n\t\t<span class=\"qodef-m-icon-inner\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-left\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.7 239l136-136c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9L127.9 256l96.4 96.4c9.4 9.4 9.4 24.6 0 33.9L201.7 409c-9.4 9.4-24.6 9.4-33.9 0l-136-136c-9.5-9.4-9.5-24.6-.1-34z\"><\/path><\/svg>\t\t\t\t\t<\/span>\n\t<\/span>\n\t<\/div>\n\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Duch Wody Flaga, maska, r\u0119kawiczka, poduszka Ducha Wody &#8211; cyjanotypie na bawe\u0142nie (r\u00f3\u017cne formaty); cykl fotografii cyfrowej; zwoje wielkoformatowe &#8211; fotografie oraz skany grafik; cyjanotypie na papierze, A4, 2024-2025 \u00a0 Posta\u0107 Ducha Wody inspirowana s\u0142owia\u0144skimi wierzeniami zwi\u0105zanymi z kultem wody i stworzeniami zamieszkuj\u0105cymi ekosystemy wodne (Wodna Panna, Rusa\u0142ka, Boginka, Dziwo\u017cona, Wi\u0142a, Brzegina, Brzeginka). Obiekty pokryte [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":967,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-989","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Spirit of Water - Marta W\u0119gli\u0144ska - water-inspired environmental art<\/title>\n<meta name=\"description\" content=\"Research-based art exploring water spirits, aquatic ecosystems and Slavic myths through cyanotype, fieldwork, photography, and performative objects.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/martaweglinska.pl\/en\/duch-wody\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spirit of Water - Marta W\u0119gli\u0144ska - water-inspired environmental art\" \/>\n<meta property=\"og:description\" content=\"Research-based art exploring water spirits, aquatic ecosystems and Slavic myths through cyanotype, fieldwork, photography, and performative objects.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/martaweglinska.pl\/en\/duch-wody\/\" \/>\n<meta property=\"og:site_name\" content=\"Marta W\u0119gli\u0144ska\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kobalt.migrating.platform\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-02T18:17:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-3-43-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1911\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/martaweglinska.pl\\\/duch-wody\\\/\",\"url\":\"https:\\\/\\\/martaweglinska.pl\\\/duch-wody\\\/\",\"name\":\"Spirit of Water - Marta W\u0119gli\u0144ska - water-inspired environmental art\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/martaweglinska.pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/martaweglinska.pl\\\/duch-wody\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/martaweglinska.pl\\\/duch-wody\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/martaweglinska.pl\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-3-43-scaled.jpg\",\"datePublished\":\"2025-11-19T20:02:40+00:00\",\"dateModified\":\"2026-02-02T18:17:31+00:00\",\"description\":\"Research-based art exploring water spirits, aquatic ecosystems and Slavic myths through cyanotype, fieldwork, photography, and performative objects.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/martaweglinska.pl\\\/duch-wody\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/martaweglinska.pl\\\/duch-wody\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/martaweglinska.pl\\\/duch-wody\\\/#primaryimage\",\"url\":\"https:\\\/\\\/martaweglinska.pl\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-3-43-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/martaweglinska.pl\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-3-43-scaled.jpg\",\"width\":2560,\"height\":1911},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/martaweglinska.pl\\\/duch-wody\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\\\/\\\/martaweglinska.pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Duch wody\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/martaweglinska.pl\\\/#website\",\"url\":\"https:\\\/\\\/martaweglinska.pl\\\/\",\"name\":\"Marta W\u0119gli\u0144ska\",\"description\":\"Portfolio\",\"publisher\":{\"@id\":\"https:\\\/\\\/martaweglinska.pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/martaweglinska.pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/martaweglinska.pl\\\/#organization\",\"name\":\"Marta W\u0119gli\u0144ska\",\"url\":\"https:\\\/\\\/martaweglinska.pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/martaweglinska.pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/martaweglinska.pl\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Marta-Weglinska-e1763409767210.png\",\"contentUrl\":\"https:\\\/\\\/martaweglinska.pl\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Marta-Weglinska-e1763409767210.png\",\"width\":1170,\"height\":640,\"caption\":\"Marta W\u0119gli\u0144ska\"},\"image\":{\"@id\":\"https:\\\/\\\/martaweglinska.pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kobalt.migrating.platform\",\"https:\\\/\\\/www.instagram.com\\\/marta.weglinska\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Spirit of Water - Marta W\u0119gli\u0144ska - water-inspired environmental art","description":"Research-based art exploring water spirits, aquatic ecosystems and Slavic myths through cyanotype, fieldwork, photography, and performative objects.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/martaweglinska.pl\/en\/duch-wody\/","og_locale":"en_GB","og_type":"article","og_title":"Spirit of Water - Marta W\u0119gli\u0144ska - water-inspired environmental art","og_description":"Research-based art exploring water spirits, aquatic ecosystems and Slavic myths through cyanotype, fieldwork, photography, and performative objects.","og_url":"https:\/\/martaweglinska.pl\/en\/duch-wody\/","og_site_name":"Marta W\u0119gli\u0144ska","article_publisher":"https:\/\/www.facebook.com\/kobalt.migrating.platform","article_modified_time":"2026-02-02T18:17:31+00:00","og_image":[{"width":2560,"height":1911,"url":"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-3-43-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/martaweglinska.pl\/duch-wody\/","url":"https:\/\/martaweglinska.pl\/duch-wody\/","name":"Spirit of Water - Marta W\u0119gli\u0144ska - water-inspired environmental art","isPartOf":{"@id":"https:\/\/martaweglinska.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/martaweglinska.pl\/duch-wody\/#primaryimage"},"image":{"@id":"https:\/\/martaweglinska.pl\/duch-wody\/#primaryimage"},"thumbnailUrl":"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-3-43-scaled.jpg","datePublished":"2025-11-19T20:02:40+00:00","dateModified":"2026-02-02T18:17:31+00:00","description":"Research-based art exploring water spirits, aquatic ecosystems and Slavic myths through cyanotype, fieldwork, photography, and performative objects.","breadcrumb":{"@id":"https:\/\/martaweglinska.pl\/duch-wody\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/martaweglinska.pl\/duch-wody\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/martaweglinska.pl\/duch-wody\/#primaryimage","url":"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-3-43-scaled.jpg","contentUrl":"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/MartaWeglinska_Spirit_of_water_Java_fot_AdhiwinantoSemali2024-3-43-scaled.jpg","width":2560,"height":1911},{"@type":"BreadcrumbList","@id":"https:\/\/martaweglinska.pl\/duch-wody\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/martaweglinska.pl\/"},{"@type":"ListItem","position":2,"name":"Duch wody"}]},{"@type":"WebSite","@id":"https:\/\/martaweglinska.pl\/#website","url":"https:\/\/martaweglinska.pl\/","name":"Marta W\u0119gli\u0144ska","description":"Portfolio","publisher":{"@id":"https:\/\/martaweglinska.pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/martaweglinska.pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/martaweglinska.pl\/#organization","name":"Marta W\u0119gli\u0144ska","url":"https:\/\/martaweglinska.pl\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/martaweglinska.pl\/#\/schema\/logo\/image\/","url":"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/Marta-Weglinska-e1763409767210.png","contentUrl":"https:\/\/martaweglinska.pl\/wp-content\/uploads\/2025\/11\/Marta-Weglinska-e1763409767210.png","width":1170,"height":640,"caption":"Marta W\u0119gli\u0144ska"},"image":{"@id":"https:\/\/martaweglinska.pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kobalt.migrating.platform","https:\/\/www.instagram.com\/marta.weglinska"]}]}},"_links":{"self":[{"href":"https:\/\/martaweglinska.pl\/en\/wp-json\/wp\/v2\/pages\/989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/martaweglinska.pl\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/martaweglinska.pl\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/martaweglinska.pl\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/martaweglinska.pl\/en\/wp-json\/wp\/v2\/comments?post=989"}],"version-history":[{"count":37,"href":"https:\/\/martaweglinska.pl\/en\/wp-json\/wp\/v2\/pages\/989\/revisions"}],"predecessor-version":[{"id":2046,"href":"https:\/\/martaweglinska.pl\/en\/wp-json\/wp\/v2\/pages\/989\/revisions\/2046"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/martaweglinska.pl\/en\/wp-json\/wp\/v2\/media\/967"}],"wp:attachment":[{"href":"https:\/\/martaweglinska.pl\/en\/wp-json\/wp\/v2\/media?parent=989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}